{"id":11593,"date":"2024-12-20T12:05:39","date_gmt":"2024-12-20T12:05:39","guid":{"rendered":"https:\/\/www.toscana-istruzione.it\/atpisa\/?p=11593"},"modified":"2024-12-20T12:05:40","modified_gmt":"2024-12-20T12:05:40","slug":"festa-della-bandiera-rotary-club-area-tirrenica-2","status":"publish","type":"post","link":"https:\/\/www.toscana-istruzione.it\/atpisa\/2024\/12\/20\/festa-della-bandiera-rotary-club-area-tirrenica-2\/","title":{"rendered":"FESTA DELLA BANDIERA &#8211; ROTARY CLUB AREA TIRRENICA 2"},"content":{"rendered":"\n<p><span style=\"font-size: 10.0pt; font-family: 'Courier New';\">Si comunica che il Distretto Rotary 2071 organizza la <b>Festa della Bandiera<\/b>, con il patrocinio del Comune di Pisa: l\u2019evento \u00e8 organizzato in collaborazione\u00a0con l&#8217;Orchestra e il Coro dell&#8217;Universit\u00e0 di Pisa, per offrire alla citt\u00e0 un <b>concerto<\/b>\u00a0sotto le <b>Logge di Banchi, marted\u00ec 7 gennaio 2025 dalle 11:30 alle 13:00.<\/b><\/span><\/p>\n<p><span style=\"font-size: 10.0pt; font-family: 'Courier New';\">I Rotary Club dell&#8217;Area Tirrenica 2 auspicano una massiccia partecipazione delle scuole di Pisa, nella prospettiva pi\u00f9 ampia di un progetto di educazione civica riguardante anche la battaglia di Curtatone e Montanara &#8211; alla quale presero parte molti studenti e docenti dell\u2019ateneo pisano.<\/span><\/p>\n<p><span style=\"font-size: 10.0pt; font-family: 'Courier New';\">In allegato Locandina dell\u2019evento.\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-content\/uploads\/2024\/12\/LOCANDINA-FESTA-DEL-TRICOLORE.pdf\" target=\"_blank\" rel=\"noopener\">LOCANDINA FESTA DEL TRICOLORE<\/a><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica che il Distretto Rotary 2071 organizza la Festa della Bandiera, con il patrocinio del Comune di Pisa: l\u2019evento \u00e8 organizzato in collaborazione\u00a0con l&#8217;Orchestra e il Coro dell&#8217;Universit\u00e0 di Pisa, per offrire alla citt\u00e0 un concerto\u00a0sotto le Logge di <a href=\"https:\/\/www.toscana-istruzione.it\/atpisa\/2024\/12\/20\/festa-della-bandiera-rotary-club-area-tirrenica-2\/\" class=\"read-more\">Leggi &#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,22,3],"tags":[],"class_list":["post-11593","post","type-post","status-publish","format-standard","hentry","category-eventi-e-progetti","category-in-evidenza","category-news"],"_links":{"self":[{"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/posts\/11593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/comments?post=11593"}],"version-history":[{"count":1,"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/posts\/11593\/revisions"}],"predecessor-version":[{"id":11595,"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/posts\/11593\/revisions\/11595"}],"wp:attachment":[{"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/media?parent=11593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/categories?post=11593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/tags?post=11593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}