{"id":12193,"date":"2025-05-13T20:14:05","date_gmt":"2025-05-13T20:14:05","guid":{"rendered":"https:\/\/www.toscana-istruzione.it\/atpisa\/?p=12193"},"modified":"2025-05-14T10:33:04","modified_gmt":"2025-05-14T10:33:04","slug":"rete-toscana-musica","status":"publish","type":"post","link":"https:\/\/www.toscana-istruzione.it\/atpisa\/2025\/05\/13\/rete-toscana-musica\/","title":{"rendered":"15 maggio 2025 &#8211; III Rassegna Regionale delle Orchestre Scolastiche"},"content":{"rendered":"\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><a href=\"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-content\/uploads\/2025\/05\/Invito-Rassegna-orchestre-15-maggio-2025-Pontedera.docx\" target=\"_blank\" rel=\"noopener\">Invito Rassegna orchestre 15 maggio 2025 Pontedera<\/a><\/li>\n<li><a href=\"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-content\/uploads\/2025\/05\/Locandina-ORCHESTRE-maggio-2025-1-1.pdf\" target=\"_blank\" rel=\"noopener\">Locandina ORCHESTRE maggio 2025 (1)-1<\/a><\/li>\n<li><a href=\"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-content\/uploads\/2025\/05\/PROGRAMMA-DI-SALA-RASSEGNA-ORCHESTRE-PONTEDERA-15-MAGGIO-2025.pdf\" target=\"_blank\" rel=\"noopener\">PROGRAMMA DI SALA RASSEGNA ORCHESTRE PONTEDERA 15 MAGGIO 2025<\/a><\/li>\n<li><a href=\"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-content\/uploads\/2025\/05\/Scaletta-Rassegna-Orchestre-Pontedera-15-maggio-2025.pdf\" target=\"_blank\" rel=\"noopener\">Scaletta Rassegna Orchestre Pontedera 15 maggio 2025<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n\n\n\n\n","protected":false},"excerpt":{"rendered":"<p>Invito Rassegna orchestre 15 maggio 2025 Pontedera Locandina ORCHESTRE maggio 2025 (1)-1 PROGRAMMA DI SALA RASSEGNA ORCHESTRE PONTEDERA 15 MAGGIO 2025 Scaletta Rassegna Orchestre Pontedera 15 maggio 2025 \u00a0 \u00a0<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,22,3],"tags":[],"class_list":["post-12193","post","type-post","status-publish","format-standard","hentry","category-eventi-e-progetti","category-in-evidenza","category-news"],"_links":{"self":[{"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/posts\/12193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/comments?post=12193"}],"version-history":[{"count":9,"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/posts\/12193\/revisions"}],"predecessor-version":[{"id":12227,"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/posts\/12193\/revisions\/12227"}],"wp:attachment":[{"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/media?parent=12193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/categories?post=12193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/tags?post=12193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}