{"id":14497,"date":"2026-01-30T12:15:33","date_gmt":"2026-01-30T11:15:33","guid":{"rendered":"https:\/\/www.toscana-istruzione.it\/atpisa\/?p=14497"},"modified":"2026-01-30T12:15:33","modified_gmt":"2026-01-30T11:15:33","slug":"interpello-per-n-1-posto-di-supplenza-scuola-infanzia-posto-sostegno-per-25-ore-settimanali-dal-2-febbraio-2026-al-30-giugno-2026","status":"publish","type":"post","link":"https:\/\/www.toscana-istruzione.it\/atpisa\/2026\/01\/30\/interpello-per-n-1-posto-di-supplenza-scuola-infanzia-posto-sostegno-per-25-ore-settimanali-dal-2-febbraio-2026-al-30-giugno-2026\/","title":{"rendered":"Interpello per n. 1 posto di supplenza Scuola Infanzia Posto Sostegno per 25 ore settimanali dal 2 Febbraio 2026 al 30 Giugno 2026"},"content":{"rendered":"\n<p><a href=\"https:\/\/madinterpello.portaleargo.it\/index.html#\/operation?codice=INT_DOC&amp;codMin=piic82600q\" target=\"_blank\" rel=\"noopener\">https:\/\/madinterpello.portaleargo.it\/index.html#\/operation?codice=INT_DOC&amp;codMin=piic82600q<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>https:\/\/madinterpello.portaleargo.it\/index.html#\/operation?codice=INT_DOC&amp;codMin=piic82600q<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,31,3],"tags":[],"class_list":["post-14497","post","type-post","status-publish","format-standard","hentry","category-in-evidenza","category-interpelli","category-news"],"_links":{"self":[{"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/posts\/14497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/comments?post=14497"}],"version-history":[{"count":1,"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/posts\/14497\/revisions"}],"predecessor-version":[{"id":14498,"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/posts\/14497\/revisions\/14498"}],"wp:attachment":[{"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/media?parent=14497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/categories?post=14497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.toscana-istruzione.it\/atpisa\/wp-json\/wp\/v2\/tags?post=14497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}